{"id":1155058,"date":"2011-05-17T17:09:15","date_gmt":"2011-05-17T14:09:15","guid":{"rendered":"https:\/\/superon.cn\/catalogue\/uncategorized\/z-05-694\/"},"modified":"2026-05-12T13:56:48","modified_gmt":"2026-05-12T10:56:48","slug":"z-05-694","status":"publish","type":"product","link":"https:\/\/superon.cn\/pb\/catalogue\/05-castors\/plastic-castors\/z-05-694\/","title":{"rendered":"Rueda de PU, con prendedor, sin soporte"},"content":{"rendered":"- Os rod\u00edzios s\u00e3o feitos de um material de pl\u00e1stico de boa qualidade.<br \/>&#8211; Os rod\u00edzios n\u00e3o deixam \u201clinhas pretas\u201d no ch\u00e3o quando s\u00e3o utilizados.<br \/>&#8211; Os rod\u00edzios n\u00e3o perdem a forma quando s\u00e3o utilizados com cargas padr\u00e3o.","protected":false},"excerpt":{"rendered":"<p>&#8211; Os rod\u00edzios s\u00e3o feitos de um material de pl\u00e1stico de boa qualidade.&#8211; Os rod\u00edzios n\u00e3o deixam \u201clinhas pretas\u201d no ch\u00e3o quando s\u00e3o utilizados.&#8211; Os rod\u00edzios n\u00e3o perdem a forma quando s\u00e3o utilizados com cargas padr\u00e3o.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[368526,368559],"product_tag":[],"class_list":{"0":"post-1155058","1":"product","2":"type-product","3":"status-publish","5":"product_cat-05-castors","6":"product_cat-plastic-castors","7":"no-featured-image-padding","8":"sales-flash-overlay","9":"woocommerce-text-align-center","10":"woocommerce-image-align-center","11":"do-quantity-buttons","13":"first","14":"instock","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/product\/1155058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/comments?post=1155058"}],"wp:attachment":[{"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/media?parent=1155058"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/product_brand?post=1155058"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/product_cat?post=1155058"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/product_tag?post=1155058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}