{"id":1149034,"date":"2007-01-07T00:00:00","date_gmt":"2007-01-06T21:00:00","guid":{"rendered":"https:\/\/superon.cn\/catalogue\/uncategorized\/10-202\/"},"modified":"2026-05-12T13:54:07","modified_gmt":"2026-05-12T10:54:07","slug":"10-202","status":"publish","type":"product","link":"https:\/\/superon.cn\/pb\/catalogue\/10-connecting-fittings\/eccentric-cams\/10-202\/","title":{"rendered":"Exc\u00e9ntrica, D15"},"content":{"rendered":"- As cames exc\u00eantricas puxam as t\u00e1buas dos m\u00f3veis no seu sitio, desde a fenda inicial at\u00e9 4 mm.<br \/>&#8211; endenta\u00e7\u00f5es internas e externas fazem com que a conex\u00e3o seja segura.<br \/>&#8211; O pino sempre \u00e9 puxado para a posi\u00e7\u00e3o central, o que d\u00e1 uma montagem precisa.<br \/>&#8211; As cames exc\u00eantricas podem ser apertadas com chave de fenda cruzada PH2 (recomendada) ou PZ2, chave de fenda plana ou uma chave Allen de 4 mm<br \/>&#8211; Utilizado para t\u00e1buas com espessura de 13, 15, 16 e 18 mm","protected":false},"excerpt":{"rendered":"<p>0qUvCZv4Z4o<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[368504,368573],"product_tag":[],"class_list":{"0":"post-1149034","1":"product","2":"type-product","3":"status-publish","5":"product_cat-10-connecting-fittings","6":"product_cat-eccentric-cams","7":"no-featured-image-padding","8":"sales-flash-overlay","9":"woocommerce-text-align-center","10":"woocommerce-image-align-center","11":"do-quantity-buttons","13":"first","14":"instock","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/product\/1149034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/comments?post=1149034"}],"wp:attachment":[{"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/media?parent=1149034"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/product_brand?post=1149034"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/product_cat?post=1149034"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/superon.cn\/pb\/wp-json\/wp\/v2\/product_tag?post=1149034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}