{"id":1165594,"date":"2019-07-29T00:00:00","date_gmt":"2019-07-28T21:00:00","guid":{"rendered":"https:\/\/superon.cn\/catalogue\/uncategorized\/04-308\/"},"modified":"2026-07-02T06:30:24","modified_gmt":"2026-07-02T03:30:24","slug":"04-308","status":"publish","type":"product","link":"https:\/\/superon.cn\/es\/catalogue\/04-legs-feet\/base-levellers-complex\/04-308\/","title":{"rendered":"Pie para mueble, de pl\u00e1stico"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[368680,368755],"product_tag":[],"class_list":{"0":"post-1165594","1":"product","2":"type-product","3":"status-publish","5":"product_cat-04-legs-feet","6":"product_cat-base-levellers-complex","7":"no-featured-image-padding","8":"sales-flash-overlay","9":"woocommerce-text-align-center","10":"woocommerce-image-align-center","11":"do-quantity-buttons","13":"first","14":"instock","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product\/1165594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/comments?post=1165594"}],"wp:attachment":[{"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/media?parent=1165594"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product_brand?post=1165594"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product_cat?post=1165594"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product_tag?post=1165594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}