{"id":1160370,"date":"2007-01-07T00:00:00","date_gmt":"2007-01-06T21:00:00","guid":{"rendered":"https:\/\/superon.cn\/catalogue\/uncategorized\/03-106\/"},"modified":"2026-07-02T06:28:55","modified_gmt":"2026-07-02T03:28:55","slug":"03-106","status":"publish","type":"product","link":"https:\/\/superon.cn\/es\/catalogue\/03-locks\/for-drawers\/03-106\/","title":{"rendered":"Cerradura de caj\u00f3n, #106"},"content":{"rendered":"La Especificaci\u00f3n de cerradura:<br \/>Z: cuerpo y barril de aleaci\u00f3n de zinc<br \/>R: cuerpo de acero, barril de aleaci\u00f3n de zinc<br \/>RP: cuerpo de acero, barril de pl\u00e1stico<\/p>\n<p>Llaves:<br \/>-sin carta:llave de acero con cabeza de pl\u00e1stico<br \/>-F: llave de acero con cabeza plegable","protected":false},"excerpt":{"rendered":"<p>La Especificaci\u00f3n de cerradura:Z: cuerpo y barril de aleaci\u00f3n de zincR: cuerpo de acero, barril de aleaci\u00f3n de zincRP: cuerpo de acero, barril de pl\u00e1stico Llaves:-sin carta:llave de acero con cabeza de pl\u00e1stico-F: llave de acero con cabeza plegable<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[368698,368773],"product_tag":[],"class_list":{"0":"post-1160370","1":"product","2":"type-product","3":"status-publish","5":"product_cat-03-locks","6":"product_cat-for-drawers","7":"no-featured-image-padding","8":"sales-flash-overlay","9":"woocommerce-text-align-center","10":"woocommerce-image-align-center","11":"do-quantity-buttons","13":"first","14":"instock","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product\/1160370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/comments?post=1160370"}],"wp:attachment":[{"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/media?parent=1160370"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product_brand?post=1160370"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product_cat?post=1160370"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product_tag?post=1160370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}