{"id":1149034,"date":"2007-01-07T00:00:00","date_gmt":"2007-01-06T21:00:00","guid":{"rendered":"https:\/\/superon.cn\/catalogue\/uncategorized\/10-202\/"},"modified":"2026-05-12T13:54:07","modified_gmt":"2026-05-12T10:54:07","slug":"10-202","status":"publish","type":"product","link":"https:\/\/superon.cn\/es\/catalogue\/10-connecting-fittings\/eccentric-cams\/10-202\/","title":{"rendered":"Exc\u00e9ntrica, D15"},"content":{"rendered":"- Las levas exc\u00e9ntricas halan  las tablas del mueble a su sitio, desde la brecha inicial hasta 4 mm.<br \/>&#8211; hendiduras internas y externas hacen que la conexi\u00f3n sea segura.<br \/>&#8211; El perno siempre es halado a una posici\u00f3n central, lo que proporciona un montaje preciso.<br \/>&#8211; Las levas exc\u00e9ntricas pueden ser apretadas con destornillador de cruz PH2 (recomendado) o PZ2, destornillador de punta plana o una llave Allen de 4 mm.<br \/>&#8211; Utilizado para tablas con grosor de 13, 15, 16 y 18mm","protected":false},"excerpt":{"rendered":"<p>0qUvCZv4Z4o<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[368504,368573],"product_tag":[],"class_list":{"0":"post-1149034","1":"product","2":"type-product","3":"status-publish","5":"product_cat-10-connecting-fittings","6":"product_cat-eccentric-cams","7":"no-featured-image-padding","8":"sales-flash-overlay","9":"woocommerce-text-align-center","10":"woocommerce-image-align-center","11":"do-quantity-buttons","13":"first","14":"instock","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product\/1149034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/comments?post=1149034"}],"wp:attachment":[{"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/media?parent=1149034"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product_brand?post=1149034"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product_cat?post=1149034"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/superon.cn\/es\/wp-json\/wp\/v2\/product_tag?post=1149034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}